{"id":5,"date":"2021-04-21T14:50:48","date_gmt":"2021-04-21T14:50:48","guid":{"rendered":"https:\/\/inteliav.pt\/blogue\/?p=5"},"modified":"2023-03-30T11:09:06","modified_gmt":"2023-03-30T11:09:06","slug":"modelo-de-trabalho-hibrido","status":"publish","type":"post","link":"https:\/\/inteliav.pt\/blogue\/modelo-de-trabalho-hibrido\/","title":{"rendered":"A sua empresa est\u00e1 pronta para o modelo de trabalho h\u00edbrido?"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"847\" height=\"475\" src=\"https:\/\/inteliav.pt\/blogue\/wp-content\/uploads\/2021\/04\/amp-Videoconferencia-EVC-1000-Intelbras.jpg\" alt=\"\" class=\"wp-image-6\" srcset=\"https:\/\/inteliav.pt\/blogue\/wp-content\/uploads\/2021\/04\/amp-Videoconferencia-EVC-1000-Intelbras.jpg 847w, https:\/\/inteliav.pt\/blogue\/wp-content\/uploads\/2021\/04\/amp-Videoconferencia-EVC-1000-Intelbras-300x168.jpg 300w, https:\/\/inteliav.pt\/blogue\/wp-content\/uploads\/2021\/04\/amp-Videoconferencia-EVC-1000-Intelbras-768x431.jpg 768w\" sizes=\"auto, (max-width: 847px) 100vw, 847px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>O trabalho remoto e flex\u00edvel tem aumentado nos \u00faltimos anos, j\u00e1 que a pandemia de COVID-19 for\u00e7ou as organiza\u00e7\u00f5es a procurar maneiras de continuar os seus neg\u00f3cios e opera\u00e7\u00f5es com seguran\u00e7a.<br>Muitas organiza\u00e7\u00f5es em todo o mundo fizeram a transi\u00e7\u00e3o para um modelo de trabalho h\u00edbrido. Pode saber mais sobre este tema em &#8211;\u00a0<a href=\"https:\/\/inteliav.pt\/blogue\/2021\/04\/22\/o-que-e-o-modelo-de-trabalho-hibrido-e-porque-e-o-futuro-do-trabalho\/\" target=\"_blank\" rel=\"noreferrer noopener\">Modelo de trabalho h\u00edbrido &#8211; o futuro do trabalho?<\/a>\u00a0<\/p>\n\n\n\n<p>Esta nova forma de trabalhar pode trazer muitos benef\u00edcios para o seu neg\u00f3cio, como colaboradores mais felizes, maior produtividade ou maior criatividade, mas apenas se tiver a infraestrutura de TI para garantir que todos os seus colaboradores comunicam de forma eficaz .<br>Infelizmente, muitas organiza\u00e7\u00f5es n\u00e3o atualizaram a sua infraestrutura de TI para suportar o modelo de trabalho h\u00edbrido e esta nova forma de trabalhar.<\/p>\n\n\n\n<p>O modelo de trabalho h\u00edbrido est\u00e1 a ganhar popularidade, mas o investimento em infraestrutura de TI est\u00e1 a ficar para tr\u00e1s.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\"><strong>Uma pesquisa sobre como a infraestrutura de Ti das empresas est\u00e3o a gerir o modelo de trabalho h\u00edbrido.<\/strong><\/h6>\n\n\n\n<p>Uma pesquisa global mostra que cerca de 82% da for\u00e7a de trabalho ter\u00e1, em m\u00e9dia, voltado ao local de trabalho em 12 a 18 meses.<\/p>\n\n\n\n<p>A pesquisa entrevistou 600 tomadores de decis\u00e3o de TI dos EUA, Canad\u00e1, Reino Unido, Alemanha e Fran\u00e7a e descobriu que a maioria das empresas sofreu com os desafios causados pela transi\u00e7\u00e3o repentina para o trabalho remoto, com 72% citando que n\u00e3o estavam totalmente preparados do ponto de vista da tecnologia.<\/p>\n\n\n\n<p>Como resultado, 56% das empresas aumentaram os or\u00e7amentos de tecnologia e 34% planeiam acelerar sua transforma\u00e7\u00e3o digital. De assinalar que o maior ponto problem\u00e1tico durante o per\u00edodo de trabalho em casa foi a quebra de comunica\u00e7\u00e3o entre as equipas (26%).<\/p>\n\n\n\n<p>Em rela\u00e7\u00e3o \u00e0 tecnologia especificamente, os entrevistados disseram que os seus principais desafios eram:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Suporte remoto de TI (35%)<\/li>\n\n\n\n<li>Solu\u00e7\u00f5es de fluxo de trabalho inadequadas (27%)<\/li>\n\n\n\n<li>Falta de ferramentas de comunica\u00e7\u00e3o e colabora\u00e7\u00e3o (22%)<\/li>\n\n\n\n<li>Falta de solu\u00e7\u00f5es baseadas em nuvem (10%).<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Que tecnologias as empresas precisam para oferecer suporte a uma for\u00e7a de trabalho h\u00edbrida de sucesso?<\/strong><\/h2>\n\n\n\n<p>Para garantir que todos os funcion\u00e1rios trabalhem de maneira produtiva, as organiza\u00e7\u00f5es que fizeram a transi\u00e7\u00e3o para um modelo de trabalho h\u00edbrido devem investir em novas tecnologias que desenvolvam a sua infraestrutura de TI a partir de uma estrat\u00e9gia puramente baseada no escrit\u00f3rio. Aqui est\u00e3o apenas algumas das muitas tecnologias que as empresas devem considerar se quiserem gerir uma for\u00e7a de trabalho h\u00edbrida de sucesso.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>AV e colabora\u00e7\u00e3o:<\/strong>\u00a0os funcion\u00e1rios podem estar a trabalhar no escrit\u00f3rio ou em casa, por isso \u00e9 importante que todos tenham acesso \u00e0s tecnologias de comunica\u00e7\u00e3o e colabora\u00e7\u00e3o. Isso inclui software de confer\u00eancia como Zoom ou Microsoft Teams, bem como salas de videoconfer\u00eancia &#8211; ZoomRoom ou salas de conv\u00edvio. As ferramentas de comunica\u00e7\u00e3o ir\u00e3o garantir que sua equipa permane\u00e7a em contacto, aumentando a produtividade.<br><\/li>\n\n\n\n<li><strong>Infraestrutura de TI aprimorada :<\/strong>\u00a0Para fazer a transi\u00e7\u00e3o para um modelo de trabalho h\u00edbrido com efic\u00e1cia \u00e9 fundamental que invista na infraestrutura de TI da sua empresa. Isso inclui tudo, desde melhorar as suas solu\u00e7\u00f5es de seguran\u00e7a, aumentar o armazenamento em nuvem e muito mais.<br><\/li>\n\n\n\n<li><strong>Hardware f\u00edsico:<\/strong>\u00a0permitir que os funcion\u00e1rios trabalhem nos seus computadores pessoais em casa n\u00e3o \u00e9 apenas um risco de seguran\u00e7a para a sua organiza\u00e7\u00e3o, mas tamb\u00e9m significa que n\u00e3o tem controlo sobre as ferramentas e tecnologias que eles est\u00e3o a usar.<br>Para qualquer funcion\u00e1rio que trabalhe fora do escrit\u00f3rio, \u00e9 importante que os seus dispositivos sejam ligados perfeitamente aos processos usados no escrit\u00f3rio.<br><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Conclus\u00e3o<\/h2>\n\n\n\n<p>Existem muitas outras tecnologias nas quais precisar\u00e1 investir para transformar a sua infraestrutura de TI, e<a href=\"https:\/\/inteliav.pt\/\" target=\"_blank\" rel=\"noreferrer noopener\"> InteliAV <\/a>pode ajudar. Entre em <a href=\"https:\/\/inteliav.pt\/contactos\" target=\"_blank\" rel=\"noreferrer noopener\">contacto<\/a> com nossa equipa de especialistas hoje . Temos anos de experi\u00eancia como fornecedor profissional de audiovisual (AV), integrando solu\u00e7\u00f5es de colabora\u00e7\u00e3o.<\/p>\n\n\n\n<ul class=\"wp-block-social-links is-style-default is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-linkedin  wp-block-social-link\"><a rel=\"noopener nofollow\" target=\"_blank\" href=\"https:\/\/www.linkedin.com\/company\/17944371\/admin\/\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19.7,3H4.3C3.582,3,3,3.582,3,4.3v15.4C3,20.418,3.582,21,4.3,21h15.4c0.718,0,1.3-0.582,1.3-1.3V4.3 C21,3.582,20.418,3,19.7,3z M8.339,18.338H5.667v-8.59h2.672V18.338z M7.004,8.574c-0.857,0-1.549-0.694-1.549-1.548 c0-0.855,0.691-1.548,1.549-1.548c0.854,0,1.547,0.694,1.547,1.548C8.551,7.881,7.858,8.574,7.004,8.574z M18.339,18.338h-2.669 v-4.177c0-0.996-0.017-2.278-1.387-2.278c-1.389,0-1.601,1.086-1.601,2.206v4.249h-2.667v-8.59h2.559v1.174h0.037 c0.356-0.675,1.227-1.387,2.526-1.387c2.703,0,3.203,1.779,3.203,4.092V18.338z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">LinkedIn<\/span><\/a><\/li>\n\n<li class=\"wp-social-link wp-social-link-facebook  wp-block-social-link\"><a rel=\"noopener nofollow\" target=\"_blank\" href=\"https:\/\/pt-pt.facebook.com\/inteliav\/\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12 2C6.5 2 2 6.5 2 12c0 5 3.7 9.1 8.4 9.9v-7H7.9V12h2.5V9.8c0-2.5 1.5-3.9 3.8-3.9 1.1 0 2.2.2 2.2.2v2.5h-1.3c-1.2 0-1.6.8-1.6 1.6V12h2.8l-.4 2.9h-2.3v7C18.3 21.1 22 17 22 12c0-5.5-4.5-10-10-10z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Facebook<\/span><\/a><\/li>\n\n<li class=\"wp-social-link wp-social-link-chain  wp-block-social-link\"><a rel=\"noopener nofollow\" target=\"_blank\" href=\"https:\/\/www.inteliav.pt\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M15.6,7.2H14v1.5h1.6c2,0,3.7,1.7,3.7,3.7s-1.7,3.7-3.7,3.7H14v1.5h1.6c2.8,0,5.2-2.3,5.2-5.2,0-2.9-2.3-5.2-5.2-5.2zM4.7,12.4c0-2,1.7-3.7,3.7-3.7H10V7.2H8.4c-2.9,0-5.2,2.3-5.2,5.2,0,2.9,2.3,5.2,5.2,5.2H10v-1.5H8.4c-2,0-3.7-1.7-3.7-3.7zm4.6.9h5.3v-1.5H9.3v1.5z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Liga\u00e7\u00e3o<\/span><\/a><\/li><\/ul>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O trabalho remoto e flex\u00edvel tem aumentado nos \u00faltimos anos, j\u00e1 que a pandemia de COVID-19 for\u00e7ou as organiza\u00e7\u00f5es a procurar maneiras de continuar os seus neg\u00f3cios e opera\u00e7\u00f5es com seguran\u00e7a.Muitas organiza\u00e7\u00f5es em todo o mundo fizeram a transi\u00e7\u00e3o para &hellip; <a href=\"https:\/\/inteliav.pt\/blogue\/modelo-de-trabalho-hibrido\/\">Continuar a ler <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[9,7],"tags":[53],"class_list":["post-5","post","type-post","status-publish","format-standard","hentry","category-trabalho-remoto","category-videoconferencia","tag-corporativo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A sua empresa est\u00e1 pronta para o modelo de trabalho h\u00edbrido?<\/title>\n<meta name=\"description\" content=\"Muitas organiza\u00e7\u00f5es em todo o mundo est\u00e3o a implementar um modelo de trabalho h\u00edbrido, onde os colaboradores trabalham em qualquer lugar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/inteliav.pt\/blogue\/modelo-de-trabalho-hibrido\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A sua empresa est\u00e1 pronta para o modelo de trabalho h\u00edbrido?\" \/>\n<meta property=\"og:description\" content=\"Muitas organiza\u00e7\u00f5es em todo o mundo est\u00e3o a implementar um modelo de trabalho h\u00edbrido, onde os colaboradores trabalham em qualquer lugar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/inteliav.pt\/blogue\/modelo-de-trabalho-hibrido\/\" \/>\n<meta property=\"og:site_name\" content=\"InteliAV - Solu\u00e7\u00f5es Audiovisuais\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/inteliavlda\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-21T14:50:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-30T11:09:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/inteliav.pt\/blogue\/wp-content\/uploads\/2021\/04\/amp-Videoconferencia-EVC-1000-Intelbras.jpg\" \/>\n<meta name=\"author\" content=\"Bruno Lu\u00eds\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bruno Lu\u00eds\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/modelo-de-trabalho-hibrido\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/modelo-de-trabalho-hibrido\\\/\"},\"author\":{\"name\":\"Bruno Lu\u00eds\",\"@id\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/#\\\/schema\\\/person\\\/326af62df6d1ae93166e570f77a77b55\"},\"headline\":\"A sua empresa est\u00e1 pronta para o modelo de trabalho h\u00edbrido?\",\"datePublished\":\"2021-04-21T14:50:48+00:00\",\"dateModified\":\"2023-03-30T11:09:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/modelo-de-trabalho-hibrido\\\/\"},\"wordCount\":690,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/modelo-de-trabalho-hibrido\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/amp-Videoconferencia-EVC-1000-Intelbras.jpg\",\"keywords\":[\"corporativo\"],\"articleSection\":[\"Trabalho remoto\",\"Videoconfer\u00eancia\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/modelo-de-trabalho-hibrido\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/modelo-de-trabalho-hibrido\\\/\",\"url\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/modelo-de-trabalho-hibrido\\\/\",\"name\":\"A sua empresa est\u00e1 pronta para o modelo de trabalho h\u00edbrido?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/modelo-de-trabalho-hibrido\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/modelo-de-trabalho-hibrido\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/amp-Videoconferencia-EVC-1000-Intelbras.jpg\",\"datePublished\":\"2021-04-21T14:50:48+00:00\",\"dateModified\":\"2023-03-30T11:09:06+00:00\",\"description\":\"Muitas organiza\u00e7\u00f5es em todo o mundo est\u00e3o a implementar um modelo de trabalho h\u00edbrido, onde os colaboradores trabalham em qualquer lugar.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/modelo-de-trabalho-hibrido\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/modelo-de-trabalho-hibrido\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/modelo-de-trabalho-hibrido\\\/#primaryimage\",\"url\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/amp-Videoconferencia-EVC-1000-Intelbras.jpg\",\"contentUrl\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/amp-Videoconferencia-EVC-1000-Intelbras.jpg\",\"width\":847,\"height\":475},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/modelo-de-trabalho-hibrido\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A sua empresa est\u00e1 pronta para o modelo de trabalho h\u00edbrido?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/#website\",\"url\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/\",\"name\":\"InteliAV - Solu\u00e7\u00f5es Audiovisuais\",\"description\":\"Um Blogue sobre integra\u00e7\u00e3o AV, design AV e muito mais.\",\"publisher\":{\"@id\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/#organization\",\"name\":\"InteliAV\",\"url\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/cropped-1519864795834-4.png\",\"contentUrl\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/cropped-1519864795834-4.png\",\"width\":153,\"height\":78,\"caption\":\"InteliAV\"},\"image\":{\"@id\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/inteliavlda\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/inteliav\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/#\\\/schema\\\/person\\\/326af62df6d1ae93166e570f77a77b55\",\"name\":\"Bruno Lu\u00eds\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8be8356bc231c959ef1f9bfa4659e53b7509ee4562d188b075364176de8c59c8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8be8356bc231c959ef1f9bfa4659e53b7509ee4562d188b075364176de8c59c8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8be8356bc231c959ef1f9bfa4659e53b7509ee4562d188b075364176de8c59c8?s=96&d=mm&r=g\",\"caption\":\"Bruno Lu\u00eds\"},\"sameAs\":[\"https:\\\/\\\/inteliav.pt\\\/blogue\"],\"url\":\"https:\\\/\\\/inteliav.pt\\\/blogue\\\/author\\\/inteliav-admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A sua empresa est\u00e1 pronta para o modelo de trabalho h\u00edbrido?","description":"Muitas organiza\u00e7\u00f5es em todo o mundo est\u00e3o a implementar um modelo de trabalho h\u00edbrido, onde os colaboradores trabalham em qualquer lugar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/inteliav.pt\/blogue\/modelo-de-trabalho-hibrido\/","og_locale":"pt_PT","og_type":"article","og_title":"A sua empresa est\u00e1 pronta para o modelo de trabalho h\u00edbrido?","og_description":"Muitas organiza\u00e7\u00f5es em todo o mundo est\u00e3o a implementar um modelo de trabalho h\u00edbrido, onde os colaboradores trabalham em qualquer lugar.","og_url":"https:\/\/inteliav.pt\/blogue\/modelo-de-trabalho-hibrido\/","og_site_name":"InteliAV - Solu\u00e7\u00f5es Audiovisuais","article_publisher":"https:\/\/www.facebook.com\/inteliavlda","article_published_time":"2021-04-21T14:50:48+00:00","article_modified_time":"2023-03-30T11:09:06+00:00","og_image":[{"url":"https:\/\/inteliav.pt\/blogue\/wp-content\/uploads\/2021\/04\/amp-Videoconferencia-EVC-1000-Intelbras.jpg","type":"","width":"","height":""}],"author":"Bruno Lu\u00eds","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Bruno Lu\u00eds","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/inteliav.pt\/blogue\/modelo-de-trabalho-hibrido\/#article","isPartOf":{"@id":"https:\/\/inteliav.pt\/blogue\/modelo-de-trabalho-hibrido\/"},"author":{"name":"Bruno Lu\u00eds","@id":"https:\/\/inteliav.pt\/blogue\/#\/schema\/person\/326af62df6d1ae93166e570f77a77b55"},"headline":"A sua empresa est\u00e1 pronta para o modelo de trabalho h\u00edbrido?","datePublished":"2021-04-21T14:50:48+00:00","dateModified":"2023-03-30T11:09:06+00:00","mainEntityOfPage":{"@id":"https:\/\/inteliav.pt\/blogue\/modelo-de-trabalho-hibrido\/"},"wordCount":690,"commentCount":0,"publisher":{"@id":"https:\/\/inteliav.pt\/blogue\/#organization"},"image":{"@id":"https:\/\/inteliav.pt\/blogue\/modelo-de-trabalho-hibrido\/#primaryimage"},"thumbnailUrl":"https:\/\/inteliav.pt\/blogue\/wp-content\/uploads\/2021\/04\/amp-Videoconferencia-EVC-1000-Intelbras.jpg","keywords":["corporativo"],"articleSection":["Trabalho remoto","Videoconfer\u00eancia"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/inteliav.pt\/blogue\/modelo-de-trabalho-hibrido\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/inteliav.pt\/blogue\/modelo-de-trabalho-hibrido\/","url":"https:\/\/inteliav.pt\/blogue\/modelo-de-trabalho-hibrido\/","name":"A sua empresa est\u00e1 pronta para o modelo de trabalho h\u00edbrido?","isPartOf":{"@id":"https:\/\/inteliav.pt\/blogue\/#website"},"primaryImageOfPage":{"@id":"https:\/\/inteliav.pt\/blogue\/modelo-de-trabalho-hibrido\/#primaryimage"},"image":{"@id":"https:\/\/inteliav.pt\/blogue\/modelo-de-trabalho-hibrido\/#primaryimage"},"thumbnailUrl":"https:\/\/inteliav.pt\/blogue\/wp-content\/uploads\/2021\/04\/amp-Videoconferencia-EVC-1000-Intelbras.jpg","datePublished":"2021-04-21T14:50:48+00:00","dateModified":"2023-03-30T11:09:06+00:00","description":"Muitas organiza\u00e7\u00f5es em todo o mundo est\u00e3o a implementar um modelo de trabalho h\u00edbrido, onde os colaboradores trabalham em qualquer lugar.","breadcrumb":{"@id":"https:\/\/inteliav.pt\/blogue\/modelo-de-trabalho-hibrido\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/inteliav.pt\/blogue\/modelo-de-trabalho-hibrido\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/inteliav.pt\/blogue\/modelo-de-trabalho-hibrido\/#primaryimage","url":"https:\/\/inteliav.pt\/blogue\/wp-content\/uploads\/2021\/04\/amp-Videoconferencia-EVC-1000-Intelbras.jpg","contentUrl":"https:\/\/inteliav.pt\/blogue\/wp-content\/uploads\/2021\/04\/amp-Videoconferencia-EVC-1000-Intelbras.jpg","width":847,"height":475},{"@type":"BreadcrumbList","@id":"https:\/\/inteliav.pt\/blogue\/modelo-de-trabalho-hibrido\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/inteliav.pt\/blogue\/"},{"@type":"ListItem","position":2,"name":"A sua empresa est\u00e1 pronta para o modelo de trabalho h\u00edbrido?"}]},{"@type":"WebSite","@id":"https:\/\/inteliav.pt\/blogue\/#website","url":"https:\/\/inteliav.pt\/blogue\/","name":"InteliAV - Solu\u00e7\u00f5es Audiovisuais","description":"Um Blogue sobre integra\u00e7\u00e3o AV, design AV e muito mais.","publisher":{"@id":"https:\/\/inteliav.pt\/blogue\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/inteliav.pt\/blogue\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/inteliav.pt\/blogue\/#organization","name":"InteliAV","url":"https:\/\/inteliav.pt\/blogue\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/inteliav.pt\/blogue\/#\/schema\/logo\/image\/","url":"https:\/\/inteliav.pt\/blogue\/wp-content\/uploads\/2021\/04\/cropped-1519864795834-4.png","contentUrl":"https:\/\/inteliav.pt\/blogue\/wp-content\/uploads\/2021\/04\/cropped-1519864795834-4.png","width":153,"height":78,"caption":"InteliAV"},"image":{"@id":"https:\/\/inteliav.pt\/blogue\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/inteliavlda","https:\/\/www.linkedin.com\/company\/inteliav\/"]},{"@type":"Person","@id":"https:\/\/inteliav.pt\/blogue\/#\/schema\/person\/326af62df6d1ae93166e570f77a77b55","name":"Bruno Lu\u00eds","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/8be8356bc231c959ef1f9bfa4659e53b7509ee4562d188b075364176de8c59c8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8be8356bc231c959ef1f9bfa4659e53b7509ee4562d188b075364176de8c59c8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8be8356bc231c959ef1f9bfa4659e53b7509ee4562d188b075364176de8c59c8?s=96&d=mm&r=g","caption":"Bruno Lu\u00eds"},"sameAs":["https:\/\/inteliav.pt\/blogue"],"url":"https:\/\/inteliav.pt\/blogue\/author\/inteliav-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/inteliav.pt\/blogue\/wp-json\/wp\/v2\/posts\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inteliav.pt\/blogue\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inteliav.pt\/blogue\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inteliav.pt\/blogue\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/inteliav.pt\/blogue\/wp-json\/wp\/v2\/comments?post=5"}],"version-history":[{"count":27,"href":"https:\/\/inteliav.pt\/blogue\/wp-json\/wp\/v2\/posts\/5\/revisions"}],"predecessor-version":[{"id":1182,"href":"https:\/\/inteliav.pt\/blogue\/wp-json\/wp\/v2\/posts\/5\/revisions\/1182"}],"wp:attachment":[{"href":"https:\/\/inteliav.pt\/blogue\/wp-json\/wp\/v2\/media?parent=5"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inteliav.pt\/blogue\/wp-json\/wp\/v2\/categories?post=5"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inteliav.pt\/blogue\/wp-json\/wp\/v2\/tags?post=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}